{"id":10140,"date":"2024-05-14T06:59:52","date_gmt":"2024-05-14T06:59:52","guid":{"rendered":"https:\/\/blogs.ua.es\/uatv\/?p=10140"},"modified":"2024-05-14T06:59:52","modified_gmt":"2024-05-14T06:59:52","slug":"nevera-del-pla-de-la-casa-serrella-3","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/uatv\/2024\/05\/14\/nevera-del-pla-de-la-casa-serrella-3\/","title":{"rendered":"Nevera del Pla de la Casa (Serrella) 3"},"content":{"rendered":"<p>Nevera del Pla de la Casa.<br \/>\nFageca, El Comtat. Sierra de Mariola.<br \/>\n1350 msnm. Di\u00e1metro: 11,5 m. Profundidad: 13 m.<br \/>\nCapacidad estimada: 1270 m3.<br \/>\nConstrucci\u00f3n: En el siglo XVII.<br \/>\nPor su gran volumen y la calidad de su construcci\u00f3n fue el pozo m\u00e1s importante de la sierra de Serrella. Principalmente abasteci\u00f3 a los pueblos del valle de Ceta, y hay constancia de que durante el siglo XVIII abasteci\u00f3 al pueblo de Alcoi, al menos en una ocasi\u00f3n, por no disponer de nieve los pozos del Carrascar de la Font Roja, que eran los que abastec\u00edan normalmente a esta ciudad.<br \/>\nFuente: Manuel Vicedo Mart\u00ednez, Jaime Ram\u00edrez Gos\u00e1lvez<br \/>\nGu\u00eda de los pozos de nieve de la provincia de Alicante<br \/>\nAlicante, Diputaci\u00f3n de Alicante, 2004. 398 p.<br \/>\nISBN 84-96206-19-X<br \/>\nV\u00eddeo  realizado por Manuel Vicedo Mart\u00ednez.<br \/>\n <iframe src=\"https:\/\/vertice.cpd.ua.es\/293126?iframef=1&vrtapp=blogsua\" style=\"display:block; width:610px; height:343.125px;\" frameBorder=\"0\"  scrolling=\"no\" allowfullscreen>iframes no soportados en este navegador<\/iframe> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nevera del Pla de la Casa. Fageca, El Comtat. Sierra de Mariola. 1350 msnm. Di\u00e1metro: 11,5 m. Profundidad: 13 m. Capacidad estimada: 1270 m3. Construcci\u00f3n: En el siglo XVII. Por su gran volumen y la calidad de su construcci\u00f3n fue el pozo m\u00e1s importante de la sierra de Serrella. Principalmente abasteci\u00f3 a los pueblos del [&hellip;]<\/p>\n","protected":false},"author":4518,"featured_media":10139,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2309424],"tags":[2379516,2379519,2379518,2379331,2379517,2379523],"class_list":["post-10140","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arte-y-humanidades","tag-cava","tag-comercio","tag-hielo","tag-nieve","tag-pozo","tag-ventisquero"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/uatv\/wp-json\/wp\/v2\/posts\/10140","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/uatv\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/uatv\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/uatv\/wp-json\/wp\/v2\/users\/4518"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/uatv\/wp-json\/wp\/v2\/comments?post=10140"}],"version-history":[{"count":1,"href":"https:\/\/blogs.ua.es\/uatv\/wp-json\/wp\/v2\/posts\/10140\/revisions"}],"predecessor-version":[{"id":10141,"href":"https:\/\/blogs.ua.es\/uatv\/wp-json\/wp\/v2\/posts\/10140\/revisions\/10141"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/uatv\/wp-json\/wp\/v2\/media\/10139"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/uatv\/wp-json\/wp\/v2\/media?parent=10140"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/uatv\/wp-json\/wp\/v2\/categories?post=10140"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/uatv\/wp-json\/wp\/v2\/tags?post=10140"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}