{"id":10247,"date":"2024-05-19T16:07:17","date_gmt":"2024-05-19T16:07:17","guid":{"rendered":"https:\/\/blogs.ua.es\/uatv\/?p=10247"},"modified":"2024-05-19T16:07:17","modified_gmt":"2024-05-19T16:07:17","slug":"workshop-descobrint-lacolliment-familiar","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/uatv\/2024\/05\/19\/workshop-descobrint-lacolliment-familiar\/","title":{"rendered":"Workshop: &#8220;Descobrint l&#8217;Acolliment Familiar&#8221;"},"content":{"rendered":"<p>Charla en la Universidad de Alicante con Motivo del D\u00eda de la Familia<\/p>\n<p>El 15 de mayo de este a\u00f1o, en la Facultad de Educaci\u00f3n de la Universidad de Alicante, celebramos una charla especial con motivo del D\u00eda de la Familia. Durante esta sesi\u00f3n, destacamos la importancia de la familia en el desarrollo integral de todos sus miembros, subrayando el valor de la incondicionalidad que ofrece una familia. Nuestro enfoque se centr\u00f3 en los menores tutelados y las familias de acogida, resaltando sus experiencias y desaf\u00edos.<\/p>\n<p>El evento cont\u00f3 con la participaci\u00f3n de numerosos agentes sociales del \u00e1mbito, incluyendo representantes de la Direcci\u00f3n Territorial de la Provincia de Alicante, compa\u00f1eros de las entidades de Fomento; Diagrama y Zarpar, y todas las asociaciones de familias como AVAF, Xiquets y Gaia. Fue una jornada enriquecedora que subray\u00f3 la colaboraci\u00f3n y el apoyo comunitario esenciales para el bienestar de los menores y sus familias de acogida.<br \/>\n <iframe src=\"https:\/\/vertice.cpd.ua.es\/293180?iframef=1&vrtapp=blogsua\" style=\"display:block; width:610px; height:343.125px;\" frameBorder=\"0\"  scrolling=\"no\" allowfullscreen>iframes no soportados en este navegador<\/iframe> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Charla en la Universidad de Alicante con Motivo del D\u00eda de la Familia El 15 de mayo de este a\u00f1o, en la Facultad de Educaci\u00f3n de la Universidad de Alicante, celebramos una charla especial con motivo del D\u00eda de la Familia. Durante esta sesi\u00f3n, destacamos la importancia de la familia en el desarrollo integral de [&hellip;]<\/p>\n","protected":false},"author":4518,"featured_media":10246,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[246],"tags":[2379564,2379566,2379563,2379565,2371165,861],"class_list":["post-10247","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencias-sociales-y-juridicas","tag-15-de-mayo","tag-acogimiento-familiar","tag-acolliment","tag-dia-de-la-familia","tag-facultad-de-educacion","tag-universidad-de-alicante"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/uatv\/wp-json\/wp\/v2\/posts\/10247","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/uatv\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/uatv\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/uatv\/wp-json\/wp\/v2\/users\/4518"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/uatv\/wp-json\/wp\/v2\/comments?post=10247"}],"version-history":[{"count":1,"href":"https:\/\/blogs.ua.es\/uatv\/wp-json\/wp\/v2\/posts\/10247\/revisions"}],"predecessor-version":[{"id":10248,"href":"https:\/\/blogs.ua.es\/uatv\/wp-json\/wp\/v2\/posts\/10247\/revisions\/10248"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/uatv\/wp-json\/wp\/v2\/media\/10246"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/uatv\/wp-json\/wp\/v2\/media?parent=10247"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/uatv\/wp-json\/wp\/v2\/categories?post=10247"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/uatv\/wp-json\/wp\/v2\/tags?post=10247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}