{"id":9865,"date":"2024-05-07T14:52:17","date_gmt":"2024-05-07T14:52:17","guid":{"rendered":"https:\/\/blogs.ua.es\/uatv\/?p=9865"},"modified":"2024-05-07T14:52:17","modified_gmt":"2024-05-07T14:52:17","slug":"caseta-de-la-neu-5","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/uatv\/2024\/05\/07\/caseta-de-la-neu-5\/","title":{"rendered":"Caseta de la Neu 5"},"content":{"rendered":"<p>Pou o Caseta de la Neu.<br \/>\nParcent, La Marina Alta. Carrascar de Parcent.<br \/>\n760 msnm. Di\u00e1metro: 12,3 m. Profundidad: 7 m.<br \/>\nCapacidad estimada: 830 m3.<br \/>\nConstrucci\u00f3n: Entre finales del siglo XVIII y principios del XIX.<br \/>\nFue un pozo para el abasto local, aunque dadas sus dimensiones tambi\u00e9n debi\u00f3 vender sus excedentes a otros pueblos de la Marina Alta.<br \/>\nFuente: Manuel Vicedo Mart\u00ednez, Jaime Ram\u00edrez Gos\u00e1lvez<br \/>\nGu\u00eda de los pozos de nieve de la provincia de Alicante<br \/>\nAlicante, Diputaci\u00f3n de Alicante, 2004. 398 p.<br \/>\nISBN 84-96206-19-X<br \/>\nV\u00eddeo  realizado por Manuel Vicedo y Jaime Ram\u00edrez.<br \/>\n <iframe src=\"https:\/\/vertice.cpd.ua.es\/292763?iframef=1&vrtapp=blogsua\" style=\"display:block; width:610px; height:343.125px;\" frameBorder=\"0\"  scrolling=\"no\" allowfullscreen>iframes no soportados en este navegador<\/iframe> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pou o Caseta de la Neu. Parcent, La Marina Alta. Carrascar de Parcent. 760 msnm. Di\u00e1metro: 12,3 m. Profundidad: 7 m. Capacidad estimada: 830 m3. Construcci\u00f3n: Entre finales del siglo XVIII y principios del XIX. Fue un pozo para el abasto local, aunque dadas sus dimensiones tambi\u00e9n debi\u00f3 vender sus excedentes a otros pueblos de [&hellip;]<\/p>\n","protected":false},"author":4518,"featured_media":9864,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2309424],"tags":[2379516,2379519,2379518,2379331,2379517,2379523],"class_list":["post-9865","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arte-y-humanidades","tag-cava","tag-comercio","tag-hielo","tag-nieve","tag-pozo","tag-ventisquero"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/uatv\/wp-json\/wp\/v2\/posts\/9865","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/uatv\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/uatv\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/uatv\/wp-json\/wp\/v2\/users\/4518"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/uatv\/wp-json\/wp\/v2\/comments?post=9865"}],"version-history":[{"count":1,"href":"https:\/\/blogs.ua.es\/uatv\/wp-json\/wp\/v2\/posts\/9865\/revisions"}],"predecessor-version":[{"id":9866,"href":"https:\/\/blogs.ua.es\/uatv\/wp-json\/wp\/v2\/posts\/9865\/revisions\/9866"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/uatv\/wp-json\/wp\/v2\/media\/9864"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/uatv\/wp-json\/wp\/v2\/media?parent=9865"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/uatv\/wp-json\/wp\/v2\/categories?post=9865"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/uatv\/wp-json\/wp\/v2\/tags?post=9865"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}