{"id":15,"date":"2007-12-03T22:14:58","date_gmt":"2007-12-03T20:14:58","guid":{"rendered":"https:\/\/blogs.ua.es\/verduset70\/2007\/12\/03\/vuelvo-a-las-andadas\/"},"modified":"2007-12-03T22:14:58","modified_gmt":"2007-12-03T20:14:58","slug":"vuelvo-a-las-andadas","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/verduset70\/2007\/12\/03\/vuelvo-a-las-andadas\/","title":{"rendered":"Vuelvo a las andadas"},"content":{"rendered":"<p><a href=\"https:\/\/blogs.ua.es\/verduset70\/files\/2007\/12\/fotomedio_uno.jpg\" title=\"Ojos del Guadiana\"><img decoding=\"async\" src=\"https:\/\/blogs.ua.es\/verduset70\/files\/2007\/12\/fotomedio_uno.thumbnail.jpg\" alt=\"Ojos del Guadiana\" \/><\/a>Vuelvo, como el Guadiana, y no creo que sea tan constante como otros bloggers, pero lo intentar\u00e9, aunque sea\u00a0una vez al mes.<\/p>\n<p>\u00a0Y temas para divulgar tengo varios, que he ido asimilando y analizando en los \u00faltimos meses: tanto a nivel docente, sobre todo en innovaci\u00f3n educativa, en gesti\u00f3n de investigaci\u00f3n, y por supuesto, sobre estrategias y t\u00e1cticas, criticables por supuesto, desde mi universidad en diversas materias (nuevos planes de estudios, reestructuraci\u00f3n de centros, gesti\u00f3n del conocimiento y la investigaci\u00f3n, etc), que espero no cometan otras instituciones, desde mi humilde punto de vista\u00a0&#8230;<\/p>\n<p>\u00a0Hasta pronto!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vuelvo, como el Guadiana, y no creo que sea tan constante como otros bloggers, pero lo intentar\u00e9, aunque sea\u00a0una vez al mes. \u00a0Y temas para divulgar tengo varios, que he ido asimilando y analizando en los \u00faltimos meses: tanto a nivel docente, sobre todo en innovaci\u00f3n educativa, en gesti\u00f3n de investigaci\u00f3n, y por supuesto, sobre [&hellip;]<\/p>\n","protected":false},"author":96,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-15","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/verduset70\/wp-json\/wp\/v2\/posts\/15","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/verduset70\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/verduset70\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/verduset70\/wp-json\/wp\/v2\/users\/96"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/verduset70\/wp-json\/wp\/v2\/comments?post=15"}],"version-history":[{"count":0,"href":"https:\/\/blogs.ua.es\/verduset70\/wp-json\/wp\/v2\/posts\/15\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/verduset70\/wp-json\/wp\/v2\/media?parent=15"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/verduset70\/wp-json\/wp\/v2\/categories?post=15"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/verduset70\/wp-json\/wp\/v2\/tags?post=15"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}