{"id":122,"date":"2012-01-25T20:45:48","date_gmt":"2012-01-25T20:45:48","guid":{"rendered":"https:\/\/blogs.ua.es\/vidaprivadafelipeii\/?p=122"},"modified":"2012-01-25T20:45:48","modified_gmt":"2012-01-25T20:45:48","slug":"gillermo-de-orange-2","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/vidaprivadafelipeii\/2012\/01\/25\/gillermo-de-orange-2\/","title":{"rendered":"Gillermo de Orange"},"content":{"rendered":"<p>El &#8220;archienemigo&#8221; de Felipe II en los Pa\u00edses Bajos.<\/p>\n<p>Guillermo I de Orange-Nassau<\/p>\n<p>(Llamado El Taciturno; Dillenburg, Alemania, 1533-Delft, actual Pa\u00edses Bajos, 1584) Pr\u00edncipe de Orange. Noble flamenco, se educ\u00f3 en la corte de Carlos I, y durante los primeros a\u00f1os del reinado de Felipe II form\u00f3 parte del Consejo de Estado de Flandes, encargado de asesorar a la princesa Margarita de Parma.<\/p>\n<p>Su oposici\u00f3n al cardenal Granvela, el principal abogado de las pretensiones centralizadoras de Felipe II, que atentaban contra los intereses de la nobleza de los Pa\u00edses Bajos, as\u00ed como su temor a las actitudes de intransigencia religiosa con los protestantes y calvinistas emanadas de la corte espa\u00f1ola, lo fueron alejando paulatinamente de su lealtad a su rey.<\/p>\n<p>Aun as\u00ed, se mostr\u00f3 indeciso durante los disturbios iconoclastas que agitaron Flandes en el a\u00f1o 1566, pero la llegada del duque de Alba con sus tercios, y la terrible represi\u00f3n ejercida con la instauraci\u00f3n del Tribunal de Tumultos que conden\u00f3 a diversos nobles flamencos como Egmont y Horn, lo obligaron a exiliarse entre los hugonotes franceses con su hermano Luis de Nassau.<\/p>\n<p>Los acontecimientos de 1572, que culminaron con la toma de Brill por los \u00abmendigos del mar\u00bb y provocaron la defecci\u00f3n de Holanda y Zelanda, propiciaron una base territorial para conducir la lucha contra Espa\u00f1a. El mot\u00edn de los tercios, que saquearon Amberes en 1576, y la hostilidad general contra Felipe II, a causa de la represi\u00f3n ejercida por el duque de Alba, fueron h\u00e1bilmente utilizados por Guillermo de Orange para atraerse a las ciudades del sur de Flandes y reunir las Diecisiete Provincias en un frente conjunto para alcanzar un acuerdo con Felipe II que salvaguardase las libertades religiosas y las instituciones de los Pa\u00edses Bajos.<br \/>\n(Llamado El Taciturno; Dillenburg, Alemania, 1533-Delft, actual Pa\u00edses Bajos, 1584) Pr\u00edncipe de Orange. Noble flamenco, se educ\u00f3 en la corte de Carlos I, y durante los primeros a\u00f1os del reinado de Felipe II form\u00f3 parte del Consejo de Estado de Flandes, encargado de asesorar a la princesa Margarita de Parma.<\/p>\n<p>Su oposici\u00f3n al cardenal Granvela, el principal abogado de las pretensiones centralizadoras de Felipe II, que atentaban contra los intereses de la nobleza de los Pa\u00edses Bajos, as\u00ed como su temor a las actitudes de intransigencia religiosa con los protestantes y calvinistas emanadas de la corte espa\u00f1ola, lo fueron alejando paulatinamente de su lealtad a su rey.<\/p>\n<p>Aun as\u00ed, se mostr\u00f3 indeciso durante los disturbios iconoclastas que agitaron Flandes en el a\u00f1o 1566, pero la llegada del duque de Alba con sus tercios, y la terrible represi\u00f3n ejercida con la instauraci\u00f3n del Tribunal de Tumultos que conden\u00f3 a diversos nobles flamencos como Egmont y Horn, lo obligaron a exiliarse entre los hugonotes franceses con su hermano Luis de Nassau.<\/p>\n<p>Los acontecimientos de 1572, que culminaron con la toma de Brill por los \u00abmendigos del mar\u00bb y provocaron la defecci\u00f3n de Holanda y Zelanda, propiciaron una base territorial para conducir la lucha contra Espa\u00f1a. El mot\u00edn de los tercios, que saquearon Amberes en 1576, y la hostilidad general contra Felipe II, a causa de la represi\u00f3n ejercida por el duque de Alba, fueron h\u00e1bilmente utilizados por Guillermo de Orange para atraerse a las ciudades del sur de Flandes y reunir las Diecisiete Provincias en un frente conjunto para alcanzar un acuerdo con Felipe II que salvaguardase las libertades religiosas y las instituciones de los Pa\u00edses Bajos.<\/p>\n<p>Esta unidad se rompi\u00f3 pronto, y los intentos de Guillermo de Orange de imponer un gobernante extranjero en la persona del duque de Anjou terminaron en fracaso. Finalmente, Felipe II lo declar\u00f3 fuera de la ley y puso precio a su cabeza. En respuesta al monarca espa\u00f1ol, Guillermo de Orange public\u00f3 su Apolog\u00eda, escrito en el que se cimenta la \u00abLeyenda Negra\u00bb contra Espa\u00f1a y en el cual defiende su lucha por la libertad. En 1583 fue asesinado por el fan\u00e1tico realista Baltasar Gerard.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El &#8220;archienemigo&#8221; de Felipe II en los Pa\u00edses Bajos. Guillermo I de Orange-Nassau (Llamado El Taciturno; Dillenburg, Alemania, 1533-Delft, actual Pa\u00edses Bajos, 1584) Pr\u00edncipe de Orange. Noble flamenco, se educ\u00f3 en la corte de Carlos I, y durante los primeros a\u00f1os del reinado de Felipe II form\u00f3 parte del Consejo de Estado de Flandes, encargado [&hellip;]<\/p>\n","protected":false},"author":2163,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[74788,28],"tags":[],"class_list":["post-122","post","type-post","status-publish","format-standard","hentry","category-aspectos-belicos","category-curiosidades"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/vidaprivadafelipeii\/wp-json\/wp\/v2\/posts\/122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/vidaprivadafelipeii\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/vidaprivadafelipeii\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/vidaprivadafelipeii\/wp-json\/wp\/v2\/users\/2163"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/vidaprivadafelipeii\/wp-json\/wp\/v2\/comments?post=122"}],"version-history":[{"count":1,"href":"https:\/\/blogs.ua.es\/vidaprivadafelipeii\/wp-json\/wp\/v2\/posts\/122\/revisions"}],"predecessor-version":[{"id":123,"href":"https:\/\/blogs.ua.es\/vidaprivadafelipeii\/wp-json\/wp\/v2\/posts\/122\/revisions\/123"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/vidaprivadafelipeii\/wp-json\/wp\/v2\/media?parent=122"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/vidaprivadafelipeii\/wp-json\/wp\/v2\/categories?post=122"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/vidaprivadafelipeii\/wp-json\/wp\/v2\/tags?post=122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}