{"id":64,"date":"2011-10-23T11:13:04","date_gmt":"2011-10-23T11:13:04","guid":{"rendered":"https:\/\/blogs.ua.es\/wangmingzhe\/?p=64"},"modified":"2011-10-23T11:13:04","modified_gmt":"2011-10-23T11:13:04","slug":"la-vida-privada-de-la-indulgencia","status":"publish","type":"post","link":"https:\/\/blogs.ua.es\/wangmingzhe\/2011\/10\/23\/la-vida-privada-de-la-indulgencia\/","title":{"rendered":"La vida privada de la indulgencia"},"content":{"rendered":"<p>Rodrigo Gebo Gorgias es propiedad de su posici\u00f3n en el futuro para comprar las condiciones necesarias para el Papa,<br \/>\nmientras tanto, su propia como los gobernantes de la Santa Sede.<br \/>\n\u00c9l y su amante \uff08Vannozza de Catanei\uff09 hab\u00eda jugado una vida voluptuosa.<br \/>\nDebido a su anterior &#8220;rom\u00e1ntica&#8221;,<br \/>\nEl Vannozza Wa los pr\u00f3ximos 20 a\u00f1os, Tim y le dio cuatro hijos.<br \/>\nSus hijos:Cesare Borgia y Lucrezia Borgia,se han convertido en una mafia peque\u00f1a.Esto es como su padre.<br \/>\nCardenal en la frecuente confusi\u00f3n de carnaval sexual, mantienen una gran cantidad de dinero,recibi\u00f3 dinero de otras personas y eliminar su culpa.A veces, incluso se perder\u00e1 los cr\u00edmenes m\u00e1s viciosos.Que ten\u00eda que perdonar a una persona que mat\u00f3 a su hija,porque esa persona le dio un mont\u00f3n de dinero.<br \/>\nCuando las personas se quejan de su comportamiento.\u00c9l me contest\u00f3:Dios no se deja que el pecador muera, sino que viven y que paguen por sus pecados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rodrigo Gebo Gorgias es propiedad de su posici\u00f3n en el futuro para comprar las condiciones necesarias para el Papa, mientras tanto, su propia como los gobernantes de la Santa Sede. \u00c9l y su amante \uff08Vannozza de Catanei\uff09 hab\u00eda jugado una vida voluptuosa. Debido a su anterior &#8220;rom\u00e1ntica&#8221;, El Vannozza Wa los pr\u00f3ximos 20 a\u00f1os, Tim [&hellip;]<\/p>\n","protected":false},"author":2200,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[676],"tags":[],"class_list":["post-64","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.ua.es\/wangmingzhe\/wp-json\/wp\/v2\/posts\/64","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ua.es\/wangmingzhe\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ua.es\/wangmingzhe\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/wangmingzhe\/wp-json\/wp\/v2\/users\/2200"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ua.es\/wangmingzhe\/wp-json\/wp\/v2\/comments?post=64"}],"version-history":[{"count":1,"href":"https:\/\/blogs.ua.es\/wangmingzhe\/wp-json\/wp\/v2\/posts\/64\/revisions"}],"predecessor-version":[{"id":69,"href":"https:\/\/blogs.ua.es\/wangmingzhe\/wp-json\/wp\/v2\/posts\/64\/revisions\/69"}],"wp:attachment":[{"href":"https:\/\/blogs.ua.es\/wangmingzhe\/wp-json\/wp\/v2\/media?parent=64"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ua.es\/wangmingzhe\/wp-json\/wp\/v2\/categories?post=64"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ua.es\/wangmingzhe\/wp-json\/wp\/v2\/tags?post=64"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}